{"id":43,"date":"2023-06-08T07:03:30","date_gmt":"2023-06-08T07:03:30","guid":{"rendered":"https:\/\/fluidwork.io\/de\/?page_id=43"},"modified":"2026-02-05T09:01:51","modified_gmt":"2026-02-05T09:01:51","slug":"ueber-uns","status":"publish","type":"page","link":"https:\/\/fluidwork.io\/de\/ueber-uns\/","title":{"rendered":"\u00dcber uns"},"content":{"rendered":"[vc_row type=&#8220;full_width_background&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;default&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; bg_color=&#8220;#ffffff&#8220; bg_image=&#8220;45&#8243; bg_position=&#8220;center bottom&#8220; background_image_loading=&#8220;default&#8220; bg_repeat=&#8220;no-repeat&#8220; scene_position=&#8220;center&#8220; top_padding=&#8220;11%&#8220; bottom_padding=&#8220;11%&#8220; text_color=&#8220;light&#8220; text_align=&#8220;left&#8220; row_border_radius=&#8220;none&#8220; row_border_radius_applies=&#8220;bg&#8220; overflow=&#8220;visible&#8220; advanced_gradient=&#8220;linear-gradient(0deg, rgb(0,0,0) 6%, rgba(0,0,0,0.21) 100%)&#8220; shape_divider_position=&#8220;bottom&#8220; bg_image_animation=&#8220;none&#8220; parallax_bg=&#8220;true&#8220; parallax_bg_speed=&#8220;fast&#8220; gradient_type=&#8220;advanced&#8220; shape_type=&#8220;&#8220; advanced_gradient_display_type=&#8220;linear&#8220;][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/2&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][vc_row_inner equal_height=&#8220;yes&#8220; content_placement=&#8220;middle&#8220; column_margin=&#8220;default&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; text_align=&#8220;left&#8220; row_position=&#8220;default&#8220; row_position_tablet=&#8220;inherit&#8220; row_position_phone=&#8220;inherit&#8220; overflow=&#8220;visible&#8220; pointer_events=&#8220;all&#8220;][vc_column_inner column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; overflow=&#8220;visible&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/1&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; enable_animation=&#8220;true&#8220; animation=&#8220;fade-in&#8220; animation_easing=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; offset=&#8220;vc_col-lg-6 vc_col-md-6 vc_col-xs-12&#8243;][vc_column_text css_animation=&#8220;fadeInUp&#8220; css=&#8220;.vc_custom_1672998238420{margin-bottom: 15px !important;}&#8220;]\n<h5>FLUID WORK<\/h5>\n[\/vc_column_text][split_line_heading animation_type=&#8220;line-reveal-by-space&#8220; font_style=&#8220;h1&#8243; line_reveal_by_space_text_effect=&#8220;default&#8220; content_alignment=&#8220;default&#8220; mobile_content_alignment=&#8220;inherit&#8220; link_target=&#8220;_self&#8220; text_content=&#8220;Wir bauen Br\u00fccken&#8220; font_size=&#8220;55&#8243; font_size_tablet=&#8220;41&#8243; font_size_phone=&#8220;31&#8243;]\n<h3>Send us your feedback<\/h3>\n<h3>We love hearing it!<\/h3>\n[\/split_line_heading][vc_custom_heading text=&#8220;Wir sind \u00fcberzeugt: Die Zukunft ist fluid!<br \/>\nUnsere Mission ist es, Br\u00fccken zwischen Unternehmen und Konsumenten zu bauen.&#8220; font_container=&#8220;tag:p|text_align:left|color:rgba(255%2C255%2C255%2C0.65)&#8220; use_theme_fonts=&#8220;yes&#8220; css=&#8220;&#8220;][\/vc_column_inner][\/vc_row_inner][\/vc_column][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/2&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][\/vc_column][\/vc_row][vc_row type=&#8220;full_width_background&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;20px&#8220; equal_height=&#8220;yes&#8220; content_placement=&#8220;middle&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; bg_color=&#8220;#000000&#8243; scene_position=&#8220;center&#8220; top_padding=&#8220;12%&#8220; constrain_group_1=&#8220;yes&#8220; bottom_padding=&#8220;12%&#8220; left_padding_desktop=&#8220;0&#8243; constrain_group_2=&#8220;yes&#8220; right_padding_desktop=&#8220;0&#8243; left_padding_phone=&#8220;14px&#8220; constrain_group_6=&#8220;yes&#8220; right_padding_phone=&#8220;14px&#8220; text_color=&#8220;dark&#8220; text_align=&#8220;left&#8220; row_border_radius=&#8220;none&#8220; row_border_radius_applies=&#8220;bg&#8220; zindex=&#8220;10&#8243; overflow=&#8220;visible&#8220; advanced_gradient_angle=&#8220;0&#8243; overlay_strength=&#8220;0.3&#8243; gradient_direction=&#8220;left_to_right&#8220; shape_divider_position=&#8220;bottom&#8220; bg_image_animation=&#8220;none&#8220; shape_type=&#8220;&#8220; gradient_type=&#8220;default&#8220;][vc_column constrain_group_100=&#8220;yes&#8220; constrain_group_101=&#8220;yes&#8220; constrain_group_102=&#8220;yes&#8220; constrain_group_103=&#8220;yes&#8220; bottom_margin_tablet=&#8220;20&#8243; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;20px&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color=&#8220;#ff1053&#8243; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; font_color=&#8220;#000000&#8243; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;15px&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; overflow=&#8220;hidden&#8220; advanced_gradient_angle=&#8220;150&#8243; width=&#8220;5\/12&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_color=&#8220;rgba(0,0,0,0.15)&#8220; column_border_style=&#8220;solid&#8220; gradient_type=&#8220;advanced&#8220; advanced_gradient_display_type=&#8220;linear&#8220; column_padding_type=&#8220;advanced&#8220;][vc_row_inner column_margin=&#8220;default&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; text_align=&#8220;left&#8220; row_position=&#8220;default&#8220; row_position_tablet=&#8220;inherit&#8220; row_position_phone=&#8220;inherit&#8220; overflow=&#8220;visible&#8220; pointer_events=&#8220;all&#8220;][vc_column_inner top_padding_desktop=&#8220;4vw&#8220; bottom_padding_desktop=&#8220;4vw&#8220; left_padding_desktop=&#8220;4vw&#8220; constrain_group_101=&#8220;yes&#8220; right_padding_desktop=&#8220;4vw&#8220; top_padding_tablet=&#8220;4vw&#8220; constrain_group_102=&#8220;yes&#8220; bottom_padding_tablet=&#8220;4vw&#8220; left_padding_tablet=&#8220;4vw&#8220; constrain_group_103=&#8220;yes&#8220; right_padding_tablet=&#8220;4vw&#8220; top_padding_phone=&#8220;4vw&#8220; constrain_group_104=&#8220;yes&#8220; bottom_padding_phone=&#8220;4vw&#8220; left_padding_phone=&#8220;4vw&#8220; constrain_group_105=&#8220;yes&#8220; right_padding_phone=&#8220;4vw&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;10px&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; overflow=&#8220;visible&#8220; advanced_gradient_angle=&#8220;0&#8243; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/1&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; gradient_type=&#8220;default&#8220; column_padding_type=&#8220;advanced&#8220;][nectar_responsive_text inherited_font_style=&#8220;default&#8220; text_color=&#8220;#ffffff&#8220; font_size_desktop=&#8220;1.8vw&#8220; font_size_tablet=&#8220;22px&#8220; font_line_height=&#8220;1.3&#8243;]\n<div class=\"wpb_text_column wpb_content_element vc_custom_1490624298920\">\n<div class=\"wpb_wrapper\">\n<h3>Die Zukunft ist Fluid<\/h3>\n<\/div>\n<\/div>\n[\/nectar_responsive_text][nectar_responsive_text inherited_font_style=&#8220;default&#8220; font_size_min=&#8220;14px&#8220; font_size_max=&#8220;20px&#8220; text_color=&#8220;#ffffff&#8220; font_size_desktop=&#8220;1.1vw&#8220; font_line_height=&#8220;1.5&#8243; text_direction=&#8220;default&#8220;]\n<p data-start=\"77\" data-end=\"279\">In den letzten Jahren hat sich die Art, wie Unternehmen agieren, stark ver\u00e4ndert. M\u00e4rkte, Trends und Technologien entwickeln sich rasant. Unternehmen m\u00fcssen agil bleiben, um wettbewerbsf\u00e4hig zu sein. Gerade im E-Commerce zeigt sich diese Dynamik besonders deutlich. Produkte sind schnell vergleichbar, der Wettbewerb ist hoch. Umso wichtiger ist eine starke Markenbildung, die Vertrauen schafft, Wiedererkennung erzeugt und nachhaltiges Wachstum erm\u00f6glicht.<\/p>\n[\/nectar_responsive_text][nectar_lottie trigger_type=&#8220;play&#8220; mobile_func=&#8220;default&#8220; loop=&#8220;true&#8220; trigger_offset=&#8220;0.00,100.00&#8243; frame_constraint=&#8220;0.00,100.00&#8243; width_desktop=&#8220;50%&#8220; width_tablet=&#8220;50%&#8220; width_phone=&#8220;50%&#8220; alignment=&#8220;center&#8220; preserve_aspect_ratio=&#8220;xMidYMid meet&#8220; json_url=&#8220;https:\/\/assets5.lottiefiles.com\/private_files\/lf30_n3at4oi7.json&#8220;][\/vc_column_inner][\/vc_row_inner][\/vc_column][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;0px&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;15px&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; advanced_gradient_angle=&#8220;0&#8243; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;7\/12&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; gradient_type=&#8220;default&#8220; column_padding_type=&#8220;default&#8220;][vc_row_inner equal_height=&#8220;yes&#8220; content_placement=&#8220;top&#8220; column_margin=&#8220;20px&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; bottom_padding=&#8220;20px&#8220; text_align=&#8220;left&#8220; row_position=&#8220;default&#8220; row_position_tablet=&#8220;inherit&#8220; row_position_phone=&#8220;inherit&#8220; overflow=&#8220;visible&#8220; pointer_events=&#8220;all&#8220; css=&#8220;.vc_custom_1659929996435{margin-bottom: 0px !important;}&#8220;][vc_column_inner top_padding_desktop=&#8220;4vw&#8220; constrain_group_100=&#8220;yes&#8220; bottom_padding_desktop=&#8220;4vw&#8220; left_padding_desktop=&#8220;4vw&#8220; constrain_group_101=&#8220;yes&#8220; right_padding_desktop=&#8220;4vw&#8220; top_padding_tablet=&#8220;8vw&#8220; constrain_group_102=&#8220;yes&#8220; bottom_padding_tablet=&#8220;8vw&#8220; left_padding_tablet=&#8220;8vw&#8220; right_padding_tablet=&#8220;50%&#8220; right_padding_phone=&#8220;40%&#8220; bottom_margin_tablet=&#8220;0&#8243; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;10px&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color=&#8220;#2ac4ea&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; font_color=&#8220;#ffffff&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;15px&#8220; column_link_target=&#8220;_self&#8220; overflow=&#8220;hidden&#8220; advanced_gradient_angle=&#8220;0&#8243; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/1&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; gradient_type=&#8220;default&#8220; column_padding_type=&#8220;advanced&#8220;][nectar_responsive_text inherited_font_style=&#8220;default&#8220; font_size_desktop=&#8220;1.8vw&#8220; font_size_tablet=&#8220;22px&#8220; font_line_height=&#8220;1.3&#8243;]\n<h3>Fluid Work wird gebraucht<\/h3>\n[\/nectar_responsive_text][nectar_responsive_text inherited_font_style=&#8220;default&#8220; font_size_min=&#8220;14px&#8220; font_size_max=&#8220;20px&#8220; font_size_desktop=&#8220;1.1vw&#8220; font_line_height=&#8220;1.5&#8243; text_direction=&#8220;default&#8220;]Da all diese Ver\u00e4nderungen rasant voranschreiten, m\u00fcssen Unternehmen ihre Organisationen kontinuierlich an neue Gegebenheiten anpassen. Gleichzeitig gibt es zeitlose Konstanten, die unabh\u00e4ngig von Trends bestehen bleiben \u2013 allen voran die Markenbildung.[\/nectar_responsive_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner column_margin=&#8220;default&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; text_align=&#8220;left&#8220; row_position=&#8220;default&#8220; row_position_tablet=&#8220;inherit&#8220; row_position_phone=&#8220;inherit&#8220; overflow=&#8220;visible&#8220; pointer_events=&#8220;all&#8220;][vc_column_inner top_padding_desktop=&#8220;4vw&#8220; constrain_group_100=&#8220;yes&#8220; bottom_padding_desktop=&#8220;4vw&#8220; left_padding_desktop=&#8220;4vw&#8220; constrain_group_101=&#8220;yes&#8220; right_padding_desktop=&#8220;4vw&#8220; top_padding_tablet=&#8220;8vw&#8220; constrain_group_102=&#8220;yes&#8220; bottom_padding_tablet=&#8220;8vw&#8220; left_padding_tablet=&#8220;8vw&#8220; constrain_group_103=&#8220;yes&#8220; right_padding_tablet=&#8220;8vw&#8220; bottom_margin=&#8220;0&#8243; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;10px&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color=&#8220;#2b2b2b&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; font_color=&#8220;#0a0000&#8243; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;20px&#8220; column_link_target=&#8220;_self&#8220; overflow=&#8220;visible&#8220; advanced_gradient_angle=&#8220;0&#8243; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/1&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_color=&#8220;rgba(0,0,0,0.15)&#8220; column_border_style=&#8220;solid&#8220; gradient_type=&#8220;default&#8220; column_padding_type=&#8220;advanced&#8220;][nectar_responsive_text inherited_font_style=&#8220;default&#8220; text_color=&#8220;#ffffff&#8220; font_size_desktop=&#8220;1.8vw&#8220; font_size_tablet=&#8220;22px&#8220; font_line_height=&#8220;1.3&#8243;]\n<h3>Atomare Performance<\/h3>\n[\/nectar_responsive_text][nectar_responsive_text inherited_font_style=&#8220;default&#8220; font_size_min=&#8220;14px&#8220; font_size_max=&#8220;20px&#8220; text_color=&#8220;#ffffff&#8220; font_size_desktop=&#8220;1.1vw&#8220; font_line_height=&#8220;1.5&#8243; text_direction=&#8220;default&#8220;]Fluid Work hat es sich zur Aufgabe gemacht, Ihrem Unternehmen zu helfen, &#8222;fluid&#8220; zu werden, sodass Sie &#8211; unter sich schnell \u00e4ndernden Bedingungen &#8211; agil sein k\u00f6nnen. Wir haben &#8222;State-of-the-Art-Methoden&#8220; ausgearbeitet und kombiniert, um Ihnen die beste L\u00f6sung zu bieten.[\/nectar_responsive_text][divider line_type=&#8220;No Line&#8220; custom_height=&#8220;1vh&#8220;][nectar_lottie trigger_type=&#8220;play&#8220; mobile_func=&#8220;default&#8220; loop=&#8220;true&#8220; trigger_offset=&#8220;0.00,100.00&#8243; frame_constraint=&#8220;0.00,100.00&#8243; speed=&#8220;0.3&#8243; width_desktop=&#8220;10%&#8220; width_tablet=&#8220;30%&#8220; width_phone=&#8220;50%&#8220; alignment=&#8220;left&#8220; preserve_aspect_ratio=&#8220;xMidYMid meet&#8220; json_url=&#8220;https:\/\/assets9.lottiefiles.com\/packages\/lf20_xyzm2dsr.json&#8220;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8220;full_width_background&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;default&#8220; equal_height=&#8220;yes&#8220; content_placement=&#8220;middle&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; bg_color=&#8220;#2b2b2b&#8220; scene_position=&#8220;center&#8220; top_padding=&#8220;12%&#8220; bottom_padding=&#8220;12%&#8220; left_padding_desktop=&#8220;0&#8243; constrain_group_2=&#8220;yes&#8220; right_padding_desktop=&#8220;0&#8243; bottom_padding_tablet=&#8220;12%&#8220; left_padding_tablet=&#8220;20vw&#8220; constrain_group_4=&#8220;yes&#8220; right_padding_tablet=&#8220;20vw&#8220; left_padding_phone=&#8220;7vw&#8220; constrain_group_6=&#8220;yes&#8220; right_padding_phone=&#8220;7vw&#8220; text_color=&#8220;dark&#8220; text_align=&#8220;left&#8220; row_border_radius=&#8220;none&#8220; row_border_radius_applies=&#8220;bg&#8220; overflow=&#8220;visible&#8220; advanced_gradient_angle=&#8220;0&#8243; overlay_strength=&#8220;0.3&#8243; gradient_direction=&#8220;left_to_right&#8220; shape_divider_position=&#8220;bottom&#8220; bg_image_animation=&#8220;none&#8220; gradient_type=&#8220;default&#8220; shape_type=&#8220;&#8220;][vc_column column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;0px&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;static&#8220; advanced_gradient_angle=&#8220;65&#8243; width=&#8220;1\/1&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; column_padding_type=&#8220;advanced&#8220; gradient_type=&#8220;advanced&#8220; advanced_gradient_display_type=&#8220;linear&#8220;][vc_row_inner column_margin=&#8220;default&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; bottom_padding=&#8220;7%&#8220; text_align=&#8220;left&#8220; row_position=&#8220;default&#8220; row_position_tablet=&#8220;inherit&#8220; row_position_phone=&#8220;inherit&#8220; overflow=&#8220;visible&#8220; pointer_events=&#8220;all&#8220;][vc_column_inner column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;0px&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; overflow=&#8220;visible&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/1&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; enable_animation=&#8220;true&#8220; animation=&#8220;fade-in&#8220; animation_easing=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; column_padding_type=&#8220;default&#8220; gradient_type=&#8220;default&#8220; animation_offset=&#8220;90%&#8220;][nectar_animated_shape shape_color=&#8220;#2ac4ea&#8220; width_desktop=&#8220;15vw&#8220; animation=&#8220;none&#8220; animation_easing=&#8220;default&#8220; animation_movement_type=&#8220;transform_y&#8220; animation_movement_intensity=&#8220;0.6&#8243; animation_movement_persist_on_mobile=&#8220;true&#8220; position_desktop=&#8220;absolute&#8220; top_position_desktop=&#8220;0&#8243; left_position_desktop=&#8220;0&#8243; translate_y_desktop=&#8220;-30%&#8220; translate_x_desktop=&#8220;-50%&#8220; zindex=&#8220;-1&#8243;][nectar_highlighted_text text_color=&#8220;#ffffff&#8220; scribble_color=&#8220;#ff1053&#8243; style=&#8220;scribble&#8220; scribble_shape=&#8220;squiggle-underline&#8220; scribble_thickness=&#8220;thick&#8220; scribble_speed=&#8220;1.8s&#8220; scribble_easing=&#8220;ease_in_out&#8220; custom_font_size=&#8220;3vw&#8220; id=&#8220;circle-highlight2&#8243; font_line_height=&#8220;1.4&#8243; font_size_tablet=&#8220;4vw&#8220; font_size_phone=&#8220;5vw&#8220;]\n<h2>Der beste Weg, um an der Spitze zu bleiben ist, sich st\u00e4ndig zu verbessern und <em>fluid zu bleiben.<\/em><\/h2>\n[\/nectar_highlighted_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8220;full_width_background&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;none&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; bg_color=&#8220;#000000&#8243; scene_position=&#8220;center&#8220; top_padding=&#8220;12%&#8220; constrain_group_1=&#8220;yes&#8220; bottom_padding=&#8220;12%&#8220; left_padding_desktop=&#8220;0%&#8220; constrain_group_2=&#8220;yes&#8220; right_padding_desktop=&#8220;0%&#8220; top_padding_tablet=&#8220;10%&#8220; bottom_padding_tablet=&#8220;20%&#8220; text_color=&#8220;dark&#8220; text_align=&#8220;left&#8220; row_border_radius=&#8220;none&#8220; row_border_radius_applies=&#8220;bg&#8220; overflow=&#8220;visible&#8220; id=&#8220;values&#8220; advanced_gradient_angle=&#8220;0&#8243; overlay_strength=&#8220;0.3&#8243; gradient_direction=&#8220;left_to_right&#8220; shape_divider_position=&#8220;bottom&#8220; bg_image_animation=&#8220;none&#8220; shape_type=&#8220;&#8220; gradient_type=&#8220;default&#8220;][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/1&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][vc_row_inner column_margin=&#8220;none&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; text_align=&#8220;left&#8220; row_position=&#8220;default&#8220; row_position_tablet=&#8220;inherit&#8220; row_position_phone=&#8220;inherit&#8220; overflow=&#8220;visible&#8220; pointer_events=&#8220;all&#8220;][vc_column_inner column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; overflow=&#8220;visible&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/1&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][split_line_heading animation_type=&#8220;line-reveal-by-space&#8220; font_style=&#8220;h1&#8243; text_color=&#8220;#ffffff&#8220; line_reveal_by_space_text_effect=&#8220;default&#8220; content_alignment=&#8220;default&#8220; mobile_content_alignment=&#8220;inherit&#8220; link_target=&#8220;_self&#8220; text_content=&#8220;Unsere Kultur&#8220; font_size=&#8220;55&#8243; font_size_tablet=&#8220;41&#8243; font_size_phone=&#8220;31&#8243;]\n<h3>Send us your feedback<\/h3>\n<h3>We love hearing it!<\/h3>\n[\/split_line_heading][\/vc_column_inner][\/vc_row_inner][vc_row_inner column_margin=&#8220;none&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; text_align=&#8220;left&#8220; row_position=&#8220;default&#8220; row_position_tablet=&#8220;inherit&#8220; row_position_phone=&#8220;inherit&#8220; overflow=&#8220;visible&#8220; pointer_events=&#8220;all&#8220;][vc_column_inner column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; overflow=&#8220;visible&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/1&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][divider line_type=&#8220;Full Width Line&#8220; line_thickness=&#8220;1&#8243; divider_color=&#8220;extra-color-gradient-1&#8243; animate=&#8220;yes&#8220; custom_height=&#8220;45&#8243;][\/vc_column_inner][\/vc_row_inner][vc_row_inner equal_height=&#8220;yes&#8220; content_placement=&#8220;middle&#8220; column_margin=&#8220;none&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; text_align=&#8220;left&#8220; row_position=&#8220;default&#8220; row_position_tablet=&#8220;inherit&#8220; row_position_phone=&#8220;inherit&#8220; overflow=&#8220;visible&#8220; pointer_events=&#8220;all&#8220;][vc_column_inner column_padding=&#8220;padding-5-percent&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;right&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;10px&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; overflow=&#8220;visible&#8220; advanced_gradient_angle=&#8220;0&#8243; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;2\/3&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; enable_animation=&#8220;true&#8220; animation=&#8220;fade-in-from-bottom&#8220; animation_easing=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; gradient_type=&#8220;default&#8220; offset=&#8220;vc_col-xs-10&#8243;][nectar_highlighted_text color_type=&#8220;gradient&#8220; highlight_color=&#8220;#ff1053&#8243; secondary_color=&#8220;#2ac4ea&#8220; text_color=&#8220;#ffffff&#8220; style=&#8220;full_text&#8220; highlight_expansion=&#8220;default&#8220; custom_font_size=&#8220;2vw&#8220; font_size_phone=&#8220;21&#8243; font_line_height=&#8220;1&#8243;]\n<h2>Labor omnia vincit (<em>Harte Arbeit besiegt alles<\/em>).<\/h2>\n[\/nectar_highlighted_text][nectar_responsive_text inherited_font_style=&#8220;default&#8220; font_size_min=&#8220;14px&#8220; font_size_max=&#8220;20px&#8220; text_color=&#8220;#ffffff&#8220; font_size_desktop=&#8220;1.1vw&#8220; font_line_height=&#8220;1.5&#8243;]Wir glauben, dass man mit vollem Einsatz und harter Arbeit alles erreichen kann.[\/nectar_responsive_text][\/vc_column_inner][vc_column_inner column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; overflow=&#8220;visible&#8220; advanced_gradient_angle=&#8220;0&#8243; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/3&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; gradient_type=&#8220;default&#8220; offset=&#8220;vc_col-xs-2&#8243;][split_line_heading animation_type=&#8220;line-reveal-by-space&#8220; font_style=&#8220;h2&#8243; text_color=&#8220;#ffffff&#8220; line_reveal_by_space_text_effect=&#8220;letter-reveal-bottom&#8220; content_alignment=&#8220;right&#8220; mobile_content_alignment=&#8220;inherit&#8220; link_target=&#8220;_self&#8220; text_content=&#8220;01&#8243; font_size=&#8220;7vw&#8220; font_line_height=&#8220;1&#8243; font_size_phone=&#8220;46&#8243; font_size_tablet=&#8220;70&#8243;][\/split_line_heading][\/vc_column_inner][\/vc_row_inner][vc_row_inner column_margin=&#8220;none&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; text_align=&#8220;left&#8220; row_position=&#8220;default&#8220; row_position_tablet=&#8220;inherit&#8220; row_position_phone=&#8220;inherit&#8220; overflow=&#8220;visible&#8220; pointer_events=&#8220;all&#8220;][vc_column_inner column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; overflow=&#8220;visible&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/1&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][divider line_type=&#8220;Full Width Line&#8220; line_thickness=&#8220;1&#8243; divider_color=&#8220;extra-color-gradient-1&#8243; animate=&#8220;yes&#8220; custom_height=&#8220;45&#8243;][\/vc_column_inner][\/vc_row_inner][vc_row_inner equal_height=&#8220;yes&#8220; content_placement=&#8220;middle&#8220; column_margin=&#8220;none&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; text_align=&#8220;left&#8220; row_position=&#8220;default&#8220; row_position_tablet=&#8220;inherit&#8220; row_position_phone=&#8220;inherit&#8220; overflow=&#8220;visible&#8220; pointer_events=&#8220;all&#8220;][vc_column_inner column_padding=&#8220;padding-5-percent&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;right&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;10px&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; overflow=&#8220;visible&#8220; advanced_gradient_angle=&#8220;0&#8243; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;2\/3&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; enable_animation=&#8220;true&#8220; animation=&#8220;fade-in-from-bottom&#8220; animation_easing=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; gradient_type=&#8220;default&#8220; offset=&#8220;vc_col-xs-10&#8243;][nectar_highlighted_text color_type=&#8220;gradient&#8220; highlight_color=&#8220;#ff1053&#8243; secondary_color=&#8220;#2ac4ea&#8220; text_color=&#8220;#ffffff&#8220; style=&#8220;full_text&#8220; highlight_expansion=&#8220;default&#8220; custom_font_size=&#8220;2vw&#8220; font_size_phone=&#8220;21&#8243; font_line_height=&#8220;1&#8243;]\n<h2><em>Fortschritt<\/em> statt Perfektion.<\/h2>\n[\/nectar_highlighted_text][nectar_responsive_text inherited_font_style=&#8220;default&#8220; font_size_min=&#8220;14px&#8220; font_size_max=&#8220;20px&#8220; text_color=&#8220;#ffffff&#8220; font_size_desktop=&#8220;1.1vw&#8220; font_line_height=&#8220;1.5&#8243;]Wir glauben, dass st\u00e4ndige Ver\u00e4nderungen der Schl\u00fcssel zum Erfolg sind.[\/nectar_responsive_text][\/vc_column_inner][vc_column_inner column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; overflow=&#8220;visible&#8220; advanced_gradient_angle=&#8220;0&#8243; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/3&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; gradient_type=&#8220;default&#8220; offset=&#8220;vc_col-xs-2&#8243;][split_line_heading animation_type=&#8220;line-reveal-by-space&#8220; font_style=&#8220;h2&#8243; text_color=&#8220;#ffffff&#8220; line_reveal_by_space_text_effect=&#8220;letter-reveal-bottom&#8220; content_alignment=&#8220;right&#8220; mobile_content_alignment=&#8220;inherit&#8220; link_target=&#8220;_self&#8220; text_content=&#8220;02&#8243; font_size=&#8220;7vw&#8220; font_line_height=&#8220;1&#8243; font_size_phone=&#8220;46&#8243; font_size_tablet=&#8220;70&#8243;][\/split_line_heading][\/vc_column_inner][\/vc_row_inner][vc_row_inner column_margin=&#8220;none&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; text_align=&#8220;left&#8220; row_position=&#8220;default&#8220; row_position_tablet=&#8220;inherit&#8220; row_position_phone=&#8220;inherit&#8220; overflow=&#8220;visible&#8220; pointer_events=&#8220;all&#8220;][vc_column_inner column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; overflow=&#8220;visible&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/1&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][divider line_type=&#8220;Full Width Line&#8220; line_thickness=&#8220;1&#8243; divider_color=&#8220;extra-color-gradient-1&#8243; animate=&#8220;yes&#8220; custom_height=&#8220;45&#8243;][\/vc_column_inner][\/vc_row_inner][vc_row_inner equal_height=&#8220;yes&#8220; content_placement=&#8220;middle&#8220; column_margin=&#8220;none&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; text_align=&#8220;left&#8220; row_position=&#8220;default&#8220; row_position_tablet=&#8220;inherit&#8220; row_position_phone=&#8220;inherit&#8220; overflow=&#8220;visible&#8220; pointer_events=&#8220;all&#8220;][vc_column_inner column_padding=&#8220;padding-5-percent&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;right&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;10px&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; overflow=&#8220;visible&#8220; advanced_gradient_angle=&#8220;0&#8243; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;2\/3&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; enable_animation=&#8220;true&#8220; animation=&#8220;fade-in-from-bottom&#8220; animation_easing=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; gradient_type=&#8220;default&#8220; offset=&#8220;vc_col-xs-10&#8243;][nectar_highlighted_text color_type=&#8220;gradient&#8220; highlight_color=&#8220;#ff1053&#8243; secondary_color=&#8220;#2ac4ea&#8220; text_color=&#8220;#ffffff&#8220; style=&#8220;full_text&#8220; highlight_expansion=&#8220;default&#8220; custom_font_size=&#8220;2vw&#8220; font_size_phone=&#8220;21&#8243; font_line_height=&#8220;1&#8243;]\n<h2>Dinge bauen, die <em>inspirieren<\/em>.<\/h2>\n[\/nectar_highlighted_text][nectar_responsive_text inherited_font_style=&#8220;default&#8220; font_size_min=&#8220;14px&#8220; font_size_max=&#8220;20px&#8220; text_color=&#8220;#ffffff&#8220; font_size_desktop=&#8220;1.1vw&#8220; font_line_height=&#8220;1.5&#8243;]Wir glauben, dass man andere nur inspirieren kann, wenn man gro\u00dfartige L\u00f6sungen schafft.[\/nectar_responsive_text][\/vc_column_inner][vc_column_inner column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; overflow=&#8220;visible&#8220; advanced_gradient_angle=&#8220;0&#8243; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/3&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; gradient_type=&#8220;default&#8220; offset=&#8220;vc_col-xs-2&#8243;][split_line_heading animation_type=&#8220;line-reveal-by-space&#8220; font_style=&#8220;h2&#8243; text_color=&#8220;#ffffff&#8220; line_reveal_by_space_text_effect=&#8220;letter-reveal-bottom&#8220; content_alignment=&#8220;right&#8220; mobile_content_alignment=&#8220;inherit&#8220; link_target=&#8220;_self&#8220; text_content=&#8220;03&#8243; font_size=&#8220;7vw&#8220; font_line_height=&#8220;1&#8243; font_size_phone=&#8220;46&#8243; font_size_tablet=&#8220;70&#8243;][\/split_line_heading][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8220;full_width_background&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;default&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; bg_color=&#8220;#2b2b2b&#8220; scene_position=&#8220;center&#8220; top_padding=&#8220;5%&#8220; bottom_padding=&#8220;5%&#8220; left_padding_desktop=&#8220;0&#8243; constrain_group_2=&#8220;yes&#8220; right_padding_desktop=&#8220;0&#8243; top_padding_tablet=&#8220;10%&#8220; constrain_group_3=&#8220;yes&#8220; bottom_padding_tablet=&#8220;10%&#8220; text_color=&#8220;dark&#8220; text_align=&#8220;left&#8220; row_border_radius=&#8220;none&#8220; row_border_radius_applies=&#8220;bg&#8220; overflow=&#8220;visible&#8220; id=&#8220;team&#8220; disable_element=&#8220;yes&#8220; advanced_gradient_angle=&#8220;0&#8243; overlay_strength=&#8220;0.3&#8243; gradient_direction=&#8220;left_to_right&#8220; shape_divider_position=&#8220;bottom&#8220; bg_image_animation=&#8220;none&#8220; gradient_type=&#8220;default&#8220; shape_type=&#8220;&#8220;][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; sticky_content=&#8220;true&#8220; sticky_content_functionality=&#8220;css&#8220; sticky_content_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; advanced_gradient_angle=&#8220;0&#8243; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/3&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; enable_animation=&#8220;true&#8220; animation=&#8220;fade-in-from-bottom&#8220; animation_easing=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; gradient_type=&#8220;default&#8220;][split_line_heading animation_type=&#8220;line-reveal-by-space&#8220; font_style=&#8220;h1&#8243; text_color=&#8220;#ffffff&#8220; line_reveal_by_space_text_effect=&#8220;none&#8220; content_alignment=&#8220;default&#8220; mobile_content_alignment=&#8220;inherit&#8220; link_target=&#8220;_self&#8220; text_content=&#8220;Faces @<br \/>\nFluid Work&#8220; font_size=&#8220;55&#8243; font_size_tablet=&#8220;41&#8243; font_size_phone=&#8220;31&#8243;][\/split_line_heading][nectar_responsive_text inherited_font_style=&#8220;default&#8220; font_size_min=&#8220;14px&#8220; font_size_max=&#8220;20px&#8220; text_color=&#8220;rgba(255,255,255,0.65)&#8220; font_size_desktop=&#8220;1.1vw&#8220; font_line_height=&#8220;1.5&#8243;]Gro\u00dfe Ideen brauchen kluge und intelligente Menschen, um sie umzusetzen. Wir arbeiten mit Fachleuten aus verschiedenen Bereichen aus der ganzen Welt zusammen.[\/nectar_responsive_text][vc_row_inner column_margin=&#8220;default&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; text_align=&#8220;left&#8220; row_position=&#8220;default&#8220; row_position_tablet=&#8220;inherit&#8220; row_position_phone=&#8220;inherit&#8220; overflow=&#8220;visible&#8220; pointer_events=&#8220;all&#8220;][vc_column_inner column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; overflow=&#8220;visible&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/1&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][\/vc_column_inner][\/vc_row_inner][\/vc_column][vc_column column_padding=&#8220;padding-6-percent&#8220; column_padding_tablet=&#8220;no-extra-padding&#8220; column_padding_phone=&#8220;no-extra-padding&#8220; column_padding_position=&#8220;left&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;0px&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; advanced_gradient_angle=&#8220;0&#8243; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;2\/3&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; gradient_type=&#8220;default&#8220;][vc_row_inner column_margin=&#8220;30px&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; text_align=&#8220;left&#8220; row_position=&#8220;default&#8220; row_position_tablet=&#8220;inherit&#8220; row_position_phone=&#8220;inherit&#8220; overflow=&#8220;visible&#8220; pointer_events=&#8220;all&#8220; css=&#8220;.vc_custom_1634415872169{margin-bottom: 0px !important;}&#8220;][vc_column_inner column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; font_color=&#8220;#ffffff&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; overflow=&#8220;visible&#8220; advanced_gradient_angle=&#8220;0&#8243; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/3&#8243; tablet_width_inherit=&#8220;small_desktop&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; gradient_type=&#8220;default&#8220; column_padding_type=&#8220;default&#8220;][team_member image_url=&#8220;141&#8243; team_memeber_style=&#8220;meta_below&#8220; link_element=&#8220;none&#8220; color=&#8220;Extra-Color-2&#8243; hide_link_arrow=&#8220;true&#8220; name=&#8220;Amin&#8220; job_position=&#8220;Managing Director&#8220;]Consectetur adipiscing elit. Etiam id mi faucibus, malesuada quam eget, facilisis turpis. Quisque ac purus erat.<\/p>\n<p>Donec id pharetra tellus, vitae vehicula dolor. Aenean leo lorem, tempor vel mauris in, interdum fringilla erat. Nam auctor sodales dapibus. Ut et nibh sed neque lobortis mollis. Cras mauris tellus, ornare sed vestibulum eu, sagittis vitae justo. Vivamus pellentesque augue in orci commodo dignissim. Fusce id mi lacus.<\/p>\n<p>Nullam ultricies mollis lorem, ac gravida diam pretium eget. Ut porttitor scelerisque lacus, a fringilla felis blandit sed.[\/team_member][\/vc_column_inner][vc_column_inner column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; font_color=&#8220;#ffffff&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; overflow=&#8220;visible&#8220; advanced_gradient_angle=&#8220;0&#8243; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/3&#8243; tablet_width_inherit=&#8220;small_desktop&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; gradient_type=&#8220;default&#8220; column_padding_type=&#8220;default&#8220;][team_member image_url=&#8220;34&#8243; team_memeber_style=&#8220;meta_below&#8220; link_element=&#8220;none&#8220; color=&#8220;Accent-Color&#8220; hide_link_arrow=&#8220;true&#8220; name=&#8220;Masiha&#8220; job_position=&#8220;Director Business Development&#8220;]Consectetur adipiscing elit. Etiam id mi faucibus, malesuada quam eget, facilisis turpis. Quisque ac purus erat.Donec id pharetra tellus, vitae vehicula dolor. Aenean leo lorem, tempor vel mauris in, interdum fringilla erat.<\/p>\n<p>Nam auctor sodales dapibus. Ut et nibh sed neque lobortis mollis. Cras mauris tellus, ornare sed vestibulum eu, sagittis vitae justo. Vivamus pellentesque augue in orci commodo dignissim. Fusce id mi lacus.<\/p>\n<p>Nullam ultricies mollis lorem, ac gravida diam pretium eget. Ut porttitor scelerisque lacus, a fringilla felis blandit sed.[\/team_member][\/vc_column_inner][vc_column_inner column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; font_color=&#8220;#ffffff&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; overflow=&#8220;visible&#8220; advanced_gradient_angle=&#8220;0&#8243; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/3&#8243; tablet_width_inherit=&#8220;small_desktop&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; gradient_type=&#8220;default&#8220; column_padding_type=&#8220;default&#8220; offset=&#8220;vc_hidden-lg vc_hidden-md vc_hidden-sm vc_hidden-xs&#8220;][team_member image_url=&#8220;46&#8243; team_memeber_style=&#8220;meta_below&#8220; link_element=&#8220;none&#8220; color=&#8220;Extra-Color-2&#8243; hide_link_arrow=&#8220;true&#8220; name=&#8220;Israr&#8220; job_position=&#8220;Director Applications &amp; Marketing&#8220;]Consectetur adipiscing elit. Etiam id mi faucibus, malesuada quam eget, facilisis turpis. Quisque ac purus erat.<\/p>\n<p>Donec id pharetra tellus, vitae vehicula dolor. Aenean leo lorem, tempor vel mauris in, interdum fringilla erat. Nam auctor sodales dapibus. Ut et nibh sed neque lobortis mollis. Cras mauris tellus, ornare sed vestibulum eu, sagittis vitae justo. Vivamus pellentesque augue in orci commodo dignissim. Fusce id mi lacus.<\/p>\n<p>Nullam ultricies mollis lorem, ac gravida diam pretium eget. Ut porttitor scelerisque lacus, a fringilla felis blandit sed.[\/team_member][\/vc_column_inner][\/vc_row_inner][vc_row_inner disable_element=&#8220;yes&#8220; column_margin=&#8220;30px&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; text_align=&#8220;left&#8220; row_position=&#8220;default&#8220; row_position_tablet=&#8220;inherit&#8220; row_position_phone=&#8220;inherit&#8220; overflow=&#8220;visible&#8220; pointer_events=&#8220;all&#8220; css=&#8220;.vc_custom_1707659690797{margin-bottom: 0px !important;}&#8220;][vc_column_inner column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; font_color=&#8220;#ffffff&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; overflow=&#8220;visible&#8220; advanced_gradient_angle=&#8220;0&#8243; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/3&#8243; tablet_width_inherit=&#8220;small_desktop&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; gradient_type=&#8220;default&#8220; column_padding_type=&#8220;default&#8220;][team_member image_url=&#8220;47&#8243; team_memeber_style=&#8220;meta_below&#8220; link_element=&#8220;none&#8220; color=&#8220;Extra-Color-2&#8243; hide_link_arrow=&#8220;true&#8220; name=&#8220;Waqar&#8220; job_position=&#8220;Head of Mobile Development&#8220;]Consectetur adipiscing elit. Etiam id mi faucibus, malesuada quam eget, facilisis turpis. Quisque ac purus erat.<\/p>\n<p>Donec id pharetra tellus, vitae vehicula dolor. Aenean leo lorem, tempor vel mauris in, interdum fringilla erat. Nam auctor sodales dapibus. Ut et nibh sed neque lobortis mollis. Cras mauris tellus, ornare sed vestibulum eu, sagittis vitae justo. Vivamus pellentesque augue in orci commodo dignissim. Fusce id mi lacus.<\/p>\n<p>Nullam ultricies mollis lorem, ac gravida diam pretium eget. Ut porttitor scelerisque lacus, a fringilla felis blandit sed.[\/team_member][\/vc_column_inner][vc_column_inner column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; font_color=&#8220;#ffffff&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; overflow=&#8220;visible&#8220; advanced_gradient_angle=&#8220;0&#8243; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/3&#8243; tablet_width_inherit=&#8220;small_desktop&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; gradient_type=&#8220;default&#8220; column_padding_type=&#8220;default&#8220;][team_member image_url=&#8220;120&#8243; team_memeber_style=&#8220;meta_below&#8220; link_element=&#8220;none&#8220; color=&#8220;Extra-Color-2&#8243; hide_link_arrow=&#8220;true&#8220; name=&#8220;Abdul-Aziz&#8220; job_position=&#8220;Full Stack Developer&#8220;]Consectetur adipiscing elit. Etiam id mi faucibus, malesuada quam eget, facilisis turpis. Quisque ac purus erat.<\/p>\n<p>Donec id pharetra tellus, vitae vehicula dolor. Aenean leo lorem, tempor vel mauris in, interdum fringilla erat. Nam auctor sodales dapibus. Ut et nibh sed neque lobortis mollis. Cras mauris tellus, ornare sed vestibulum eu, sagittis vitae justo. Vivamus pellentesque augue in orci commodo dignissim. Fusce id mi lacus.<\/p>\n<p>Nullam ultricies mollis lorem, ac gravida diam pretium eget. Ut porttitor scelerisque lacus, a fringilla felis blandit sed.[\/team_member][\/vc_column_inner][vc_column_inner column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; font_color=&#8220;#ffffff&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; overflow=&#8220;visible&#8220; advanced_gradient_angle=&#8220;0&#8243; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/3&#8243; tablet_width_inherit=&#8220;small_desktop&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; gradient_type=&#8220;default&#8220; column_padding_type=&#8220;default&#8220;][team_member image_url=&#8220;48&#8243; team_memeber_style=&#8220;meta_below&#8220; link_element=&#8220;none&#8220; color=&#8220;Extra-Color-2&#8243; hide_link_arrow=&#8220;true&#8220; name=&#8220;Verda&#8220; job_position=&#8220;UX &amp; UI Designer&#8220;]Consectetur adipiscing elit. Etiam id mi faucibus, malesuada quam eget, facilisis turpis. Quisque ac purus erat.<\/p>\n<p>Donec id pharetra tellus, vitae vehicula dolor. Aenean leo lorem, tempor vel mauris in, interdum fringilla erat. Nam auctor sodales dapibus. Ut et nibh sed neque lobortis mollis. Cras mauris tellus, ornare sed vestibulum eu, sagittis vitae justo. Vivamus pellentesque augue in orci commodo dignissim. Fusce id mi lacus.<\/p>\n<p>Nullam ultricies mollis lorem, ac gravida diam pretium eget. Ut porttitor scelerisque lacus, a fringilla felis blandit sed.[\/team_member][\/vc_column_inner][\/vc_row_inner][vc_row_inner disable_element=&#8220;yes&#8220; column_margin=&#8220;30px&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; text_align=&#8220;left&#8220; row_position=&#8220;default&#8220; row_position_tablet=&#8220;inherit&#8220; row_position_phone=&#8220;inherit&#8220; overflow=&#8220;visible&#8220; pointer_events=&#8220;all&#8220; css=&#8220;.vc_custom_1707659698905{margin-bottom: 0px !important;}&#8220;][vc_column_inner column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; font_color=&#8220;#ffffff&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; overflow=&#8220;visible&#8220; advanced_gradient_angle=&#8220;0&#8243; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/3&#8243; tablet_width_inherit=&#8220;small_desktop&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; gradient_type=&#8220;default&#8220; column_padding_type=&#8220;default&#8220;][team_member image_url=&#8220;50&#8243; team_memeber_style=&#8220;meta_below&#8220; link_element=&#8220;none&#8220; color=&#8220;Extra-Color-2&#8243; hide_link_arrow=&#8220;true&#8220; name=&#8220;Galang&#8220; job_position=&#8220;3D Artist &amp; Animator&#8220;]Consectetur adipiscing elit. Etiam id mi faucibus, malesuada quam eget, facilisis turpis. Quisque ac purus erat.<\/p>\n<p>Donec id pharetra tellus, vitae vehicula dolor. Aenean leo lorem, tempor vel mauris in, interdum fringilla erat. Nam auctor sodales dapibus. Ut et nibh sed neque lobortis mollis. Cras mauris tellus, ornare sed vestibulum eu, sagittis vitae justo. Vivamus pellentesque augue in orci commodo dignissim. Fusce id mi lacus.<\/p>\n<p>Nullam ultricies mollis lorem, ac gravida diam pretium eget. Ut porttitor scelerisque lacus, a fringilla felis blandit sed.[\/team_member][\/vc_column_inner][vc_column_inner column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; font_color=&#8220;#ffffff&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; overflow=&#8220;visible&#8220; advanced_gradient_angle=&#8220;0&#8243; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/3&#8243; tablet_width_inherit=&#8220;small_desktop&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; gradient_type=&#8220;default&#8220; column_padding_type=&#8220;default&#8220;][team_member image_url=&#8220;51&#8243; team_memeber_style=&#8220;meta_below&#8220; link_element=&#8220;none&#8220; color=&#8220;Extra-Color-2&#8243; hide_link_arrow=&#8220;true&#8220; name=&#8220;Eri&#8220; job_position=&#8220;Graphic Designer&#8220;]Consectetur adipiscing elit. Etiam id mi faucibus, malesuada quam eget, facilisis turpis. Quisque ac purus erat.<\/p>\n<p>Donec id pharetra tellus, vitae vehicula dolor. Aenean leo lorem, tempor vel mauris in, interdum fringilla erat. Nam auctor sodales dapibus. Ut et nibh sed neque lobortis mollis. Cras mauris tellus, ornare sed vestibulum eu, sagittis vitae justo. Vivamus pellentesque augue in orci commodo dignissim. Fusce id mi lacus.<\/p>\n<p>Nullam ultricies mollis lorem, ac gravida diam pretium eget. Ut porttitor scelerisque lacus, a fringilla felis blandit sed.[\/team_member][\/vc_column_inner][vc_column_inner column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; font_color=&#8220;#ffffff&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; overflow=&#8220;visible&#8220; advanced_gradient_angle=&#8220;0&#8243; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/3&#8243; tablet_width_inherit=&#8220;small_desktop&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; gradient_type=&#8220;default&#8220; column_padding_type=&#8220;default&#8220;][team_member image_url=&#8220;49&#8243; team_memeber_style=&#8220;meta_below&#8220; link_element=&#8220;none&#8220; color=&#8220;Extra-Color-2&#8243; hide_link_arrow=&#8220;true&#8220; name=&#8220;Shumaila&#8220; job_position=&#8220;UX &amp; UI Designer&#8220;]Consectetur adipiscing elit. Etiam id mi faucibus, malesuada quam eget, facilisis turpis. Quisque ac purus erat.<\/p>\n<p>Donec id pharetra tellus, vitae vehicula dolor. Aenean leo lorem, tempor vel mauris in, interdum fringilla erat. Nam auctor sodales dapibus. Ut et nibh sed neque lobortis mollis. Cras mauris tellus, ornare sed vestibulum eu, sagittis vitae justo. Vivamus pellentesque augue in orci commodo dignissim. Fusce id mi lacus.<\/p>\n<p>Nullam ultricies mollis lorem, ac gravida diam pretium eget. Ut porttitor scelerisque lacus, a fringilla felis blandit sed.[\/team_member][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8220;full_width_background&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;default&#8220; equal_height=&#8220;yes&#8220; content_placement=&#8220;middle&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; bg_color=&#8220;#000000&#8243; scene_position=&#8220;center&#8220; top_padding=&#8220;70&#8243; bottom_padding=&#8220;70&#8243; text_color=&#8220;light&#8220; text_align=&#8220;left&#8220; row_border_radius=&#8220;none&#8220; row_border_radius_applies=&#8220;bg&#8220; overflow=&#8220;visible&#8220; advanced_gradient=&#8220;linear-gradient(146deg, rgb(255, 16, 83) 10%, rgb(42, 196, 234) 90%)&#8220; advanced_gradient_angle=&#8220;146&#8243; shape_divider_position=&#8220;bottom&#8220; bg_image_animation=&#8220;none&#8220; shape_type=&#8220;&#8220; gradient_type=&#8220;advanced&#8220; advanced_gradient_display_type=&#8220;linear&#8220;][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;center&#8220; phone_text_alignment=&#8220;center&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/2&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][split_line_heading animation_type=&#8220;line-reveal-by-space&#8220; font_style=&#8220;h2&#8243; line_reveal_by_space_text_effect=&#8220;default&#8220; content_alignment=&#8220;default&#8220; mobile_content_alignment=&#8220;inherit&#8220; link_target=&#8220;_self&#8220; text_content=&#8220;M\u00f6chten Sie Organisationen<br \/>\nund Branchen ver\u00e4ndern?&#8220;][\/split_line_heading][\/vc_column][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;center&#8220; phone_text_alignment=&#8220;center&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/2&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][vc_row_inner column_margin=&#8220;default&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; text_align=&#8220;right&#8220; row_position=&#8220;default&#8220; row_position_tablet=&#8220;inherit&#8220; row_position_phone=&#8220;inherit&#8220; overflow=&#8220;visible&#8220; pointer_events=&#8220;all&#8220;][vc_column_inner column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; overflow=&#8220;visible&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/1&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][nectar_cta btn_style=&#8220;arrow-animation&#8220; heading_tag=&#8220;h4&#8243; button_color=&#8220;accent-color&#8220; text_color=&#8220;#ffffff&#8220; button_border_thickness=&#8220;0px&#8220; link_type=&#8220;new_tab&#8220; alignment=&#8220;left&#8220; alignment_tablet=&#8220;default&#8220; alignment_phone=&#8220;default&#8220; display=&#8220;inline&#8220; display_tablet=&#8220;inherit&#8220; display_phone=&#8220;inherit&#8220; link_text=&#8220;Jetzt mitmachen!&#8220; url=&#8220;mailto:info@fluidwork.io&#8220; padding_top=&#8220;20&#8243; padding_right=&#8220;40&#8243; padding_bottom=&#8220;20&#8243; padding_left=&#8220;40&#8243;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=&#8220;full_width_background&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;default&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; bg_color=&#8220;#ffffff&#8220; bg_image=&#8220;45&#8243; bg_position=&#8220;center bottom&#8220; background_image_loading=&#8220;default&#8220; bg_repeat=&#8220;no-repeat&#8220; scene_position=&#8220;center&#8220; top_padding=&#8220;11%&#8220;&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-43","page","type-page","status-publish"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00dcber uns - FLUID WORK | Deutschland<\/title>\n<meta name=\"description\" content=\"Wir sind \u00fcberzeugt: Die Zukunft ist fluid!Unsere Mission ist es, Br\u00fccken zwischen der alten und der neuen (digitalen) Arbeitsweise zu bauen.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fluidwork.io\/de\/ueber-uns\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00dcber uns - FLUID WORK | Deutschland\" \/>\n<meta property=\"og:description\" content=\"Wir sind \u00fcberzeugt: Die Zukunft ist fluid!Unsere Mission ist es, Br\u00fccken zwischen der alten und der neuen (digitalen) Arbeitsweise zu bauen.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fluidwork.io\/de\/ueber-uns\/\" \/>\n<meta property=\"og:site_name\" content=\"FLUID WORK | Deutschland\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-05T09:01:51+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"18\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fluidwork.io\\\/de\\\/ueber-uns\\\/\",\"url\":\"https:\\\/\\\/fluidwork.io\\\/de\\\/ueber-uns\\\/\",\"name\":\"\u00dcber uns - FLUID WORK | Deutschland\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fluidwork.io\\\/de\\\/#website\"},\"datePublished\":\"2023-06-08T07:03:30+00:00\",\"dateModified\":\"2026-02-05T09:01:51+00:00\",\"description\":\"Wir sind \u00fcberzeugt: Die Zukunft ist fluid!Unsere Mission ist es, Br\u00fccken zwischen der alten und der neuen (digitalen) Arbeitsweise zu bauen.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fluidwork.io\\\/de\\\/ueber-uns\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fluidwork.io\\\/de\\\/ueber-uns\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fluidwork.io\\\/de\\\/ueber-uns\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/fluidwork.io\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00dcber uns\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fluidwork.io\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/fluidwork.io\\\/de\\\/\",\"name\":\"FLUID WORK | Deutschland\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/fluidwork.io\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fluidwork.io\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fluidwork.io\\\/de\\\/#organization\",\"name\":\"FLUID WORK | Aslam & Arsalan GbR\",\"url\":\"https:\\\/\\\/fluidwork.io\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/fluidwork.io\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/fluidwork.io\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2023\\\/06\\\/FW_2x.png\",\"contentUrl\":\"https:\\\/\\\/fluidwork.io\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2023\\\/06\\\/FW_2x.png\",\"width\":108,\"height\":50,\"caption\":\"FLUID WORK | Aslam & Arsalan GbR\"},\"image\":{\"@id\":\"https:\\\/\\\/fluidwork.io\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/fluidwork-io\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00dcber uns - FLUID WORK | Deutschland","description":"Wir sind \u00fcberzeugt: Die Zukunft ist fluid!Unsere Mission ist es, Br\u00fccken zwischen der alten und der neuen (digitalen) Arbeitsweise zu bauen.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fluidwork.io\/de\/ueber-uns\/","og_locale":"de_DE","og_type":"article","og_title":"\u00dcber uns - FLUID WORK | Deutschland","og_description":"Wir sind \u00fcberzeugt: Die Zukunft ist fluid!Unsere Mission ist es, Br\u00fccken zwischen der alten und der neuen (digitalen) Arbeitsweise zu bauen.","og_url":"https:\/\/fluidwork.io\/de\/ueber-uns\/","og_site_name":"FLUID WORK | Deutschland","article_modified_time":"2026-02-05T09:01:51+00:00","twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"18\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/fluidwork.io\/de\/ueber-uns\/","url":"https:\/\/fluidwork.io\/de\/ueber-uns\/","name":"\u00dcber uns - FLUID WORK | Deutschland","isPartOf":{"@id":"https:\/\/fluidwork.io\/de\/#website"},"datePublished":"2023-06-08T07:03:30+00:00","dateModified":"2026-02-05T09:01:51+00:00","description":"Wir sind \u00fcberzeugt: Die Zukunft ist fluid!Unsere Mission ist es, Br\u00fccken zwischen der alten und der neuen (digitalen) Arbeitsweise zu bauen.","breadcrumb":{"@id":"https:\/\/fluidwork.io\/de\/ueber-uns\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fluidwork.io\/de\/ueber-uns\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/fluidwork.io\/de\/ueber-uns\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/fluidwork.io\/de\/"},{"@type":"ListItem","position":2,"name":"\u00dcber uns"}]},{"@type":"WebSite","@id":"https:\/\/fluidwork.io\/de\/#website","url":"https:\/\/fluidwork.io\/de\/","name":"FLUID WORK | Deutschland","description":"","publisher":{"@id":"https:\/\/fluidwork.io\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fluidwork.io\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/fluidwork.io\/de\/#organization","name":"FLUID WORK | Aslam & Arsalan GbR","url":"https:\/\/fluidwork.io\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/fluidwork.io\/de\/#\/schema\/logo\/image\/","url":"https:\/\/fluidwork.io\/de\/wp-content\/uploads\/sites\/2\/2023\/06\/FW_2x.png","contentUrl":"https:\/\/fluidwork.io\/de\/wp-content\/uploads\/sites\/2\/2023\/06\/FW_2x.png","width":108,"height":50,"caption":"FLUID WORK | Aslam & Arsalan GbR"},"image":{"@id":"https:\/\/fluidwork.io\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/fluidwork-io"]}]}},"_links":{"self":[{"href":"https:\/\/fluidwork.io\/de\/wp-json\/wp\/v2\/pages\/43","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fluidwork.io\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/fluidwork.io\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/fluidwork.io\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/fluidwork.io\/de\/wp-json\/wp\/v2\/comments?post=43"}],"version-history":[{"count":20,"href":"https:\/\/fluidwork.io\/de\/wp-json\/wp\/v2\/pages\/43\/revisions"}],"predecessor-version":[{"id":1486,"href":"https:\/\/fluidwork.io\/de\/wp-json\/wp\/v2\/pages\/43\/revisions\/1486"}],"wp:attachment":[{"href":"https:\/\/fluidwork.io\/de\/wp-json\/wp\/v2\/media?parent=43"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}